{"id":4751,"date":"2020-03-05T16:20:20","date_gmt":"2020-03-05T15:20:20","guid":{"rendered":"http:\/\/www.musicanet.org\/?p=4751"},"modified":"2020-03-05T16:20:20","modified_gmt":"2020-03-05T15:20:20","slug":"la-biblioteca-musical-de-la-catedral-de-estrasburgo-en-linea-en-musica","status":"publish","type":"post","link":"https:\/\/www.musicanet.org\/es\/actu-es\/la-biblioteca-musical-de-la-catedral-de-estrasburgo-en-linea-en-musica\/","title":{"rendered":"La biblioteca musical de la catedral de Estrasburgo en linea en Musica !"},"content":{"rendered":"<p>De aqu\u00ed en adelante, el fondo documentario de la bibliot\u00e9ca musical de catedral de Estrasburgo es administrado directamente en Musica. As\u00ed, mas de 25.000 partituras estan referenciadas y localizadas en Musica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De aqu\u00ed en adelante, el fondo documentario de la bibliot\u00e9ca musical de catedral de Estrasburgo es administrado directamente en Musica. As\u00ed, mas de 25.000 partituras estan referenciadas y localizadas en Musica.<\/p>\n","protected":false},"author":14174,"featured_media":4312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[33],"tags":[],"class_list":["post-4751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-es","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/posts\/4751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/users\/14174"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/comments?post=4751"}],"version-history":[{"count":0,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/posts\/4751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/media\/4312"}],"wp:attachment":[{"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/media?parent=4751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/categories?post=4751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.musicanet.org\/es\/wp-json\/wp\/v2\/tags?post=4751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}